{"id":10427,"date":"2017-12-12T15:50:24","date_gmt":"2017-12-12T13:50:24","guid":{"rendered":"https:\/\/senas.lengvoji.lt\/?post_type=tribe_events&#038;p=10427"},"modified":"2024-08-29T15:32:55","modified_gmt":"2024-08-29T12:32:55","slug":"lietuvos-vaiku-taures-varzybos-miestu-grupeje-3","status":"publish","type":"tribe_events","link":"https:\/\/lengvoji.lt\/en\/event\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\/","title":{"rendered":"Lietuvos vaik\u0173 taur\u0117s var\u017eybos miest\u0173 grup\u0117je"},"content":{"rendered":"<p><a href=\"https:\/\/senas.lengvoji.lt\/wp-content\/uploads\/2018\/10\/p20181109OVm.docx\" target=\"_blank\" rel=\"noopener noreferrer\">Programa<\/a><\/p>\n<p><a href=\"https:\/\/senas.lengvoji.lt\/wp-content\/uploads\/2018\/11\/20181109_OVm.xls\" target=\"_blank\" rel=\"noopener noreferrer\">Rezultatai<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programa Rezultatai<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[46],"class_list":["post-10427","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-bendri","cat_bendri"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lietuvos vaik\u0173 taur\u0117s var\u017eybos miest\u0173 grup\u0117je &#8211; LLAF Kalendorius<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lengvoji.lt\/en\/event\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lietuvos vaik\u0173 taur\u0117s var\u017eybos miest\u0173 grup\u0117je &#8211; LLAF Kalendorius\" \/>\n<meta property=\"og:description\" content=\"Programa Rezultatai\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lengvoji.lt\/en\/event\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\/\" \/>\n<meta property=\"og:site_name\" content=\"LLAF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LietuvosLengvosiosAtletikosFederacija\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T12:32:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lengvoji.lt\/wp-content\/uploads\/2024\/10\/llaf-seo-horizontal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/event\\\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\\\/\",\"url\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/event\\\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\\\/\",\"name\":\"Lietuvos vaik\u0173 taur\u0117s var\u017eybos miest\u0173 grup\u0117je &#8211; LLAF Kalendorius\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/#website\"},\"datePublished\":\"2017-12-12T13:50:24+00:00\",\"dateModified\":\"2024-08-29T12:32:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/event\\\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lengvoji.lt\\\/en\\\/event\\\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/event\\\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/beginning\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calendar\",\"item\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/kalendorius\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Common\",\"item\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/kalendorius\\\/category\\\/common\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Lietuvos vaik\u0173 taur\u0117s var\u017eybos miest\u0173 grup\u0117je\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/\",\"name\":\"Lietuvos lengvosios atletikos federacija\",\"description\":\"The National Lithuanian Athletics Organization oversees the country's athletics activities.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/#organization\"},\"alternateName\":\"LLAF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/#organization\",\"name\":\"Athletics Federation of Lithuania\",\"alternateName\":\"LLAF\",\"url\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lengvoji.lt\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/llaf-seo-square.jpg\",\"contentUrl\":\"https:\\\/\\\/lengvoji.lt\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/llaf-seo-square.jpg\",\"width\":1400,\"height\":1400,\"caption\":\"Athletics Federation of Lithuania\"},\"image\":{\"@id\":\"https:\\\/\\\/lengvoji.lt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LietuvosLengvosiosAtletikosFederacija\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lengvoji\\\/\",\"https:\\\/\\\/youtube.com\\\/@Lietuvoslengvosiosatletikosfed\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lietuvos vaik\u0173 taur\u0117s var\u017eybos miest\u0173 grup\u0117je &#8211; LLAF Kalendorius","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lengvoji.lt\/en\/event\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\/","og_locale":"en_US","og_type":"article","og_title":"Lietuvos vaik\u0173 taur\u0117s var\u017eybos miest\u0173 grup\u0117je &#8211; LLAF Kalendorius","og_description":"Programa Rezultatai","og_url":"https:\/\/lengvoji.lt\/en\/event\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\/","og_site_name":"LLAF","article_publisher":"https:\/\/www.facebook.com\/LietuvosLengvosiosAtletikosFederacija\/","article_modified_time":"2024-08-29T12:32:55+00:00","og_image":[{"width":2400,"height":1350,"url":"https:\/\/lengvoji.lt\/wp-content\/uploads\/2024\/10\/llaf-seo-horizontal.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/lengvoji.lt\/en\/event\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\/","url":"https:\/\/lengvoji.lt\/en\/event\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\/","name":"Lietuvos vaik\u0173 taur\u0117s var\u017eybos miest\u0173 grup\u0117je &#8211; LLAF Kalendorius","isPartOf":{"@id":"https:\/\/lengvoji.lt\/en\/#website"},"datePublished":"2017-12-12T13:50:24+00:00","dateModified":"2024-08-29T12:32:55+00:00","breadcrumb":{"@id":"https:\/\/lengvoji.lt\/en\/event\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lengvoji.lt\/en\/event\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lengvoji.lt\/en\/event\/lietuvos-vaiku-taures-varzybos-miestu-grupeje-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lengvoji.lt\/en\/beginning\/"},{"@type":"ListItem","position":2,"name":"Calendar","item":"https:\/\/lengvoji.lt\/en\/kalendorius\/"},{"@type":"ListItem","position":3,"name":"Common","item":"https:\/\/lengvoji.lt\/en\/kalendorius\/category\/common\/"},{"@type":"ListItem","position":4,"name":"Lietuvos vaik\u0173 taur\u0117s var\u017eybos miest\u0173 grup\u0117je"}]},{"@type":"WebSite","@id":"https:\/\/lengvoji.lt\/en\/#website","url":"https:\/\/lengvoji.lt\/en\/","name":"Lietuvos lengvosios atletikos federacija","description":"The National Lithuanian Athletics Organization oversees the country's athletics activities.","publisher":{"@id":"https:\/\/lengvoji.lt\/en\/#organization"},"alternateName":"LLAF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lengvoji.lt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lengvoji.lt\/en\/#organization","name":"Athletics Federation of Lithuania","alternateName":"LLAF","url":"https:\/\/lengvoji.lt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lengvoji.lt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lengvoji.lt\/wp-content\/uploads\/2024\/10\/llaf-seo-square.jpg","contentUrl":"https:\/\/lengvoji.lt\/wp-content\/uploads\/2024\/10\/llaf-seo-square.jpg","width":1400,"height":1400,"caption":"Athletics Federation of Lithuania"},"image":{"@id":"https:\/\/lengvoji.lt\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LietuvosLengvosiosAtletikosFederacija\/","https:\/\/www.instagram.com\/lengvoji\/","https:\/\/youtube.com\/@Lietuvoslengvosiosatletikosfed"]}]}},"_links":{"self":[{"href":"https:\/\/lengvoji.lt\/en\/wp-json\/wp\/v2\/tribe_events\/10427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lengvoji.lt\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/lengvoji.lt\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/lengvoji.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/lengvoji.lt\/en\/wp-json\/wp\/v2\/tribe_events\/10427\/revisions"}],"wp:attachment":[{"href":"https:\/\/lengvoji.lt\/en\/wp-json\/wp\/v2\/media?parent=10427"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lengvoji.lt\/en\/wp-json\/wp\/v2\/tags?post=10427"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/lengvoji.lt\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}